{"id":10405,"date":"2020-03-30T08:22:47","date_gmt":"2021-03-30T14:42:05","guid":{"rendered":"https:\/\/zughundesport-shop.de\/produkt\/uncategorized\/stainless-steel-chain-connector\/"},"modified":"2021-03-30T16:42:05","modified_gmt":"2021-03-30T14:42:05","slug":"edelstahl-kettenverbinder-2","status":"publish","type":"product","link":"https:\/\/zughundesport-shop.de\/en\/produkt\/karabiner-mehr\/edelstahl-kettenverbinder-2\/","title":{"rendered":"Stainless Steel Chain Connector"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":7640,"template":"","meta":[],"product_brand":[],"product_cat":[370],"product_tag":[],"class_list":["post-10405","product","type-product","status-publish","has-post-thumbnail","product_cat-karabiner-mehr","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.3 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Stainless Steel Chain Connector - Sledwork Shop<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zughundesport-shop.de\/en\/produkt\/karabiner-mehr\/edelstahl-kettenverbinder-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stainless Steel Chain Connector\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zughundesport-shop.de\/en\/produkt\/karabiner-mehr\/edelstahl-kettenverbinder-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Sledwork Shop\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Sledwork\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zughundesport-shop.de\/wp-content\/uploads\/2020\/03\/Kettenverbinder.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/produkt\\\/karabiner-mehr\\\/edelstahl-kettenverbinder-2\\\/\",\"url\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/produkt\\\/karabiner-mehr\\\/edelstahl-kettenverbinder-2\\\/\",\"name\":\"Stainless Steel Chain Connector - Sledwork Shop\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/produkt\\\/karabiner-mehr\\\/edelstahl-kettenverbinder-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/produkt\\\/karabiner-mehr\\\/edelstahl-kettenverbinder-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zughundesport-shop.de\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Kettenverbinder.jpg\",\"datePublished\":\"2021-03-30T14:42:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/produkt\\\/karabiner-mehr\\\/edelstahl-kettenverbinder-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/produkt\\\/karabiner-mehr\\\/edelstahl-kettenverbinder-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/produkt\\\/karabiner-mehr\\\/edelstahl-kettenverbinder-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zughundesport-shop.de\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Kettenverbinder.jpg\",\"contentUrl\":\"https:\\\/\\\/zughundesport-shop.de\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/Kettenverbinder.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/produkt\\\/karabiner-mehr\\\/edelstahl-kettenverbinder-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Stainless Steel Chain Connector\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/\",\"name\":\"Sledwork Shop\",\"description\":\"GET ALL YOU NEED FOR PERFECT DOG SPORTS\",\"publisher\":{\"@id\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/#organization\",\"name\":\"SLEDWORK\u00ae\",\"url\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zughundesport-shop.de\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo_sledwork.png\",\"contentUrl\":\"https:\\\/\\\/zughundesport-shop.de\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/logo_sledwork.png\",\"width\":765,\"height\":283,\"caption\":\"SLEDWORK\u00ae\"},\"image\":{\"@id\":\"https:\\\/\\\/zughundesport-shop.de\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Sledwork\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sledwork.de\\\/?hl=de\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Stainless Steel Chain Connector - Sledwork Shop","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zughundesport-shop.de\/en\/produkt\/karabiner-mehr\/edelstahl-kettenverbinder-2\/","og_locale":"en_US","og_type":"article","og_title":"Stainless Steel Chain Connector","og_url":"https:\/\/zughundesport-shop.de\/en\/produkt\/karabiner-mehr\/edelstahl-kettenverbinder-2\/","og_site_name":"Sledwork Shop","article_publisher":"https:\/\/www.facebook.com\/Sledwork\/","og_image":[{"width":1200,"height":1200,"url":"https:\/\/zughundesport-shop.de\/wp-content\/uploads\/2020\/03\/Kettenverbinder.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zughundesport-shop.de\/en\/produkt\/karabiner-mehr\/edelstahl-kettenverbinder-2\/","url":"https:\/\/zughundesport-shop.de\/en\/produkt\/karabiner-mehr\/edelstahl-kettenverbinder-2\/","name":"Stainless Steel Chain Connector - Sledwork Shop","isPartOf":{"@id":"https:\/\/zughundesport-shop.de\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zughundesport-shop.de\/en\/produkt\/karabiner-mehr\/edelstahl-kettenverbinder-2\/#primaryimage"},"image":{"@id":"https:\/\/zughundesport-shop.de\/en\/produkt\/karabiner-mehr\/edelstahl-kettenverbinder-2\/#primaryimage"},"thumbnailUrl":"https:\/\/zughundesport-shop.de\/wp-content\/uploads\/2020\/03\/Kettenverbinder.jpg","datePublished":"2021-03-30T14:42:05+00:00","breadcrumb":{"@id":"https:\/\/zughundesport-shop.de\/en\/produkt\/karabiner-mehr\/edelstahl-kettenverbinder-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zughundesport-shop.de\/en\/produkt\/karabiner-mehr\/edelstahl-kettenverbinder-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zughundesport-shop.de\/en\/produkt\/karabiner-mehr\/edelstahl-kettenverbinder-2\/#primaryimage","url":"https:\/\/zughundesport-shop.de\/wp-content\/uploads\/2020\/03\/Kettenverbinder.jpg","contentUrl":"https:\/\/zughundesport-shop.de\/wp-content\/uploads\/2020\/03\/Kettenverbinder.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/zughundesport-shop.de\/en\/produkt\/karabiner-mehr\/edelstahl-kettenverbinder-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zughundesport-shop.de\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/zughundesport-shop.de\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"Stainless Steel Chain Connector"}]},{"@type":"WebSite","@id":"https:\/\/zughundesport-shop.de\/en\/#website","url":"https:\/\/zughundesport-shop.de\/en\/","name":"Sledwork Shop","description":"GET ALL YOU NEED FOR PERFECT DOG SPORTS","publisher":{"@id":"https:\/\/zughundesport-shop.de\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zughundesport-shop.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zughundesport-shop.de\/en\/#organization","name":"SLEDWORK\u00ae","url":"https:\/\/zughundesport-shop.de\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zughundesport-shop.de\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zughundesport-shop.de\/wp-content\/uploads\/2019\/09\/logo_sledwork.png","contentUrl":"https:\/\/zughundesport-shop.de\/wp-content\/uploads\/2019\/09\/logo_sledwork.png","width":765,"height":283,"caption":"SLEDWORK\u00ae"},"image":{"@id":"https:\/\/zughundesport-shop.de\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Sledwork\/","https:\/\/www.instagram.com\/sledwork.de\/?hl=de"]}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/zughundesport-shop.de\/en\/wp-json\/wp\/v2\/product\/10405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zughundesport-shop.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zughundesport-shop.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zughundesport-shop.de\/en\/wp-json\/wp\/v2\/media\/7640"}],"wp:attachment":[{"href":"https:\/\/zughundesport-shop.de\/en\/wp-json\/wp\/v2\/media?parent=10405"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zughundesport-shop.de\/en\/wp-json\/wp\/v2\/product_brand?post=10405"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zughundesport-shop.de\/en\/wp-json\/wp\/v2\/product_cat?post=10405"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zughundesport-shop.de\/en\/wp-json\/wp\/v2\/product_tag?post=10405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}